{"id":1067,"date":"2026-01-08T17:40:14","date_gmt":"2026-01-08T17:40:14","guid":{"rendered":"https:\/\/ugtfgvalicante.com\/?p=1067"},"modified":"2026-01-08T17:40:15","modified_gmt":"2026-01-08T17:40:15","slug":"la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026","status":"publish","type":"post","link":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/","title":{"rendered":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El DOGV publica el decreto por el que se prorrogan hasta el 30 de junio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Generalitat mantendr\u00e1 hasta el 30 de junio de 2026 las reducciones temporales de las tarifas en los servicios p\u00fablicos de transporte auton\u00f3mico, seg\u00fan recoge el decreto ley publicado el \u00faltimo d\u00eda del a\u00f1o 2025 en el Diario Oficial de la Generalitat Valenciana (DOGV), y que permite prorrogar las condiciones previstas en el decreto ley 9\/2025, de 25 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta medida afecta a las reducciones temporales de tarifas en los abonos de transporte y t\u00edtulos multiviaje emitidos por la Autoridad de Transporte Metropolitano de Val\u00e8ncia (ATMV), al sistema TAM de Alicante y del transporte metropolitano de la Plana en Castell\u00f3n, as\u00ed como de los t\u00edtulos de transporte propios de la red de Metrovalencia y de la red del TRAM de Alicante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo decreto, aprobado el pasado viernes por el pleno del Consell, tiene como objetivo seguir facilitando el acceso al transporte p\u00fablico, promover una movilidad sostenible y aliviar el impacto econ\u00f3mico sobre la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta pr\u00f3rroga se mantiene la gratuidad temporal del transporte para la poblaci\u00f3n infantil, hasta los 14 a\u00f1os inclusive, y el t\u00edtulo dirigido a las personas empadronadas en determinados municipios afectados por la Dana de octubre de 2024, que mantiene su validez hasta el 31 de diciembre de 2026, sin necesidad de realizar ninguna recarga o proceso de actualizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta pr\u00f3rroga en los descuentos responde a la estrategia de la recuperaci\u00f3n a las zonas afectadas por las inundaciones, con el objeto de continuar ofreciendo a todos los vecinos de estos municipios beneficios concretos durante el proceso de vuelta a la normalidad. En este sentido, se han entregado durante 2025 un total de 222.539 tarjeras de transporte gratuito Recuperem Val\u00e8ncia y se han realizado cerca de 19 millones de validaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, en los pr\u00f3ximos seis meses se mantiene el descuento del 50 % en los t\u00edtulos destinados a j\u00f3venes y una reducci\u00f3n del 40 % por ciento en los abonos y t\u00edtulos multiviaje de los transportes auton\u00f3micos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De este modo, para la poblaci\u00f3n joven se mantiene en Valencia una tarifa plana para viajar de manera ilimitada por 14,90 euros al mes; en Alicante, la tarifa joven de 30 viajes mensuales ser\u00e1 de 10,60 euros; y en Castell\u00f3n, el abono temporal 30 Joven IVA, tendr\u00e1 un coste mensual de 12,75 euros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo decreto establece que la tarifa habitual de los t\u00edtulos con bonificaciones parciales o totales se corresponde con la tarifa vigente a 31 de diciembre de 2025 para cada origen-destino o, en su caso combinaci\u00f3n zonal, que sea de aplicaci\u00f3n en cada \u00e1mbito para los abonos y t\u00edtulos multiviaje o, en su defecto, el billete sencillo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El decreto ley prev\u00e9 que en el caso de que el Estado apruebe ayudas para descuentos en el transporte p\u00fablico durante el periodo de vigencia de esta pr\u00f3rroga, los descuentos auton\u00f3micos podr\u00e1n adaptarse mediante resoluci\u00f3n para ajustarse a las condiciones que establezca la normativa estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el decreto regula igualmente las indemnizaciones que la Generalitat deber\u00e1 compensar a los concesionarios de los servicios p\u00fablicos de transporte por la aplicaci\u00f3n de estas medidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.todoalicante.es\/economia\/generalitat-fija-precios-ayudas-transporte-alicante-2026-20251231062111-nt.html\">TodoAlicante<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.todoalicante.es\/autor\/jose-vicente-perez-pardo-5559.html\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El DOGV publica el decreto por el que se prorrogan hasta el 30 de junio La Generalitat mantendr\u00e1 hasta el 30 de junio de 2026 <a class=\"mh-excerpt-more\" href=\"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/\" title=\"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":4,"featured_media":1068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante\" \/>\n<meta property=\"og:description\" content=\"El DOGV publica el decreto por el que se prorrogan hasta el 30 de junio La Generalitat mantendr\u00e1 hasta el 30 de junio de 2026 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"FGV Alicante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/ugt.fgvalicante\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T17:40:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T17:40:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ugt FGV Alicante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ugt FGV Alicante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/\"},\"author\":{\"name\":\"Ugt FGV Alicante\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#\\\/schema\\\/person\\\/a1375a9c1ef53e624aa79c34b93b62e8\"},\"headline\":\"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026\",\"datePublished\":\"2026-01-08T17:40:14+00:00\",\"dateModified\":\"2026-01-08T17:40:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp\",\"articleSection\":[\"Noticias prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/\",\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/\",\"name\":\"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp\",\"datePublished\":\"2026-01-08T17:40:14+00:00\",\"dateModified\":\"2026-01-08T17:40:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp\",\"contentUrl\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp\",\"width\":1200,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/2026\\\/01\\\/08\\\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ugtfgvalicante.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#website\",\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/\",\"name\":\"FGV Alicante\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ugtfgvalicante.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#organization\",\"name\":\"UGT FGV Alicante\",\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-ugt-web.png\",\"contentUrl\":\"https:\\\/\\\/ugtfgvalicante.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-ugt-web.png\",\"width\":2283,\"height\":1126,\"caption\":\"UGT FGV Alicante\"},\"image\":{\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/ugt.fgvalicante\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ugtfgvalicante.com\\\/#\\\/schema\\\/person\\\/a1375a9c1ef53e624aa79c34b93b62e8\",\"name\":\"Ugt FGV Alicante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g\",\"caption\":\"Ugt FGV Alicante\"},\"url\":\"https:\\\/\\\/ugtfgvalicante.com\\\/index.php\\\/author\\\/ggrau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/","og_locale":"es_ES","og_type":"article","og_title":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante","og_description":"El DOGV publica el decreto por el que se prorrogan hasta el 30 de junio La Generalitat mantendr\u00e1 hasta el 30 de junio de 2026 [...]","og_url":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/","og_site_name":"FGV Alicante","article_publisher":"https:\/\/es-es.facebook.com\/ugt.fgvalicante\/","article_published_time":"2026-01-08T17:40:14+00:00","article_modified_time":"2026-01-08T17:40:15+00:00","og_image":[{"width":1200,"height":840,"url":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp","type":"image\/webp"}],"author":"Ugt FGV Alicante","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ugt FGV Alicante","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#article","isPartOf":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/"},"author":{"name":"Ugt FGV Alicante","@id":"https:\/\/ugtfgvalicante.com\/#\/schema\/person\/a1375a9c1ef53e624aa79c34b93b62e8"},"headline":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026","datePublished":"2026-01-08T17:40:14+00:00","dateModified":"2026-01-08T17:40:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/"},"wordCount":551,"publisher":{"@id":"https:\/\/ugtfgvalicante.com\/#organization"},"image":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp","articleSection":["Noticias prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/","url":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/","name":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026 - FGV Alicante","isPartOf":{"@id":"https:\/\/ugtfgvalicante.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#primaryimage"},"image":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp","datePublished":"2026-01-08T17:40:14+00:00","dateModified":"2026-01-08T17:40:15+00:00","breadcrumb":{"@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#primaryimage","url":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp","contentUrl":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2026\/01\/Tarifas-Alicante-kDTF-U2407121520128LE-1200x840@TodoAlicante.webp","width":1200,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/ugtfgvalicante.com\/index.php\/2026\/01\/08\/la-generalitat-fija-los-precios-y-las-ayudas-al-transporte-en-alicante-para-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ugtfgvalicante.com\/"},{"@type":"ListItem","position":2,"name":"La Generalitat fija los precios y las ayudas al transporte en Alicante para 2026"}]},{"@type":"WebSite","@id":"https:\/\/ugtfgvalicante.com\/#website","url":"https:\/\/ugtfgvalicante.com\/","name":"FGV Alicante","description":"","publisher":{"@id":"https:\/\/ugtfgvalicante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ugtfgvalicante.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ugtfgvalicante.com\/#organization","name":"UGT FGV Alicante","url":"https:\/\/ugtfgvalicante.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ugtfgvalicante.com\/#\/schema\/logo\/image\/","url":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2022\/10\/logo-ugt-web.png","contentUrl":"https:\/\/ugtfgvalicante.com\/wp-content\/uploads\/2022\/10\/logo-ugt-web.png","width":2283,"height":1126,"caption":"UGT FGV Alicante"},"image":{"@id":"https:\/\/ugtfgvalicante.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/ugt.fgvalicante\/"]},{"@type":"Person","@id":"https:\/\/ugtfgvalicante.com\/#\/schema\/person\/a1375a9c1ef53e624aa79c34b93b62e8","name":"Ugt FGV Alicante","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea41cd8456808460c6c0caa1a213c3c921573555df6b57a7ee2f16fb6f502866?s=96&d=mm&r=g","caption":"Ugt FGV Alicante"},"url":"https:\/\/ugtfgvalicante.com\/index.php\/author\/ggrau\/"}]}},"_links":{"self":[{"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/posts\/1067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/comments?post=1067"}],"version-history":[{"count":1,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/posts\/1067\/revisions"}],"predecessor-version":[{"id":1069,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/posts\/1067\/revisions\/1069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/media\/1068"}],"wp:attachment":[{"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/media?parent=1067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/categories?post=1067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ugtfgvalicante.com\/index.php\/wp-json\/wp\/v2\/tags?post=1067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}